{"id":95,"date":"2021-03-18T18:36:10","date_gmt":"2021-03-18T17:36:10","guid":{"rendered":"https:\/\/www.lidealeallestimenti.it\/?page_id=95"},"modified":"2021-04-30T11:30:15","modified_gmt":"2021-04-30T09:30:15","slug":"showroom-negozi","status":"publish","type":"page","link":"https:\/\/www.lidealeallestimenti.it\/en\/retail-showroom\/","title":{"rendered":"Showroom &amp; Shops"},"content":{"rendered":"<div class=\"wp-block-group portfolio__subtitle\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h5 class=\"has-text-align-center wp-block-heading\">Design, set-up and bespoke furnishings of exhibition spaces<\/h5>\n\n\n\n<p class=\"has-text-align-center\">Commercial areas, pubs, restaurants, workplace and meeting rooms, temporary shop e showroom. Solution always\ninnovated, developed meeting the customer\u2019 budget and requirements.<\/p>\n<\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"616\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-920x616.jpg\" alt=\"\" data-id=\"261\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/1-that_s-italy-3\/\" class=\"wp-image-261\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-920x616.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-600x402.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-768x514.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3.jpg 1494w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">THAT\u2019S ITALIA &#8211; Flagship store &#8211; Roma<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"615\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2-615x920.jpg\" alt=\"\" data-id=\"262\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/2-that_s-italy-2\/\" class=\"wp-image-262\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2-615x920.jpg 615w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2-401x600.jpg 401w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/2-THAT_S-ITALY-2.jpg 669w\" sizes=\"(max-width: 615px) 100vw, 615px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">THAT\u2019S ITALIA &#8211; Flagship store &#8211; Roma<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"616\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1-920x616.jpg\" alt=\"\" data-id=\"282\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/22-that_s-italy-1\/\" class=\"wp-image-282\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1-920x616.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1-600x402.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1-768x514.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/22-THAT_S-ITALY-1.jpg 1494w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">THAT\u2019S ITALIA &#8211; Flagship store &#8211; Roma<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"616\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3-920x616.jpg\" alt=\"\" data-id=\"263\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/3-texta-showroom-3\/\" class=\"wp-image-263\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3-920x616.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3-600x402.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3-768x514.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/3-TEXTA-SHOWROOM-3.jpg 1494w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">TEXTA &#8211; Showroom e uffici &#8211; Mercallo \/ Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4-920x920.jpg\" alt=\"\" data-id=\"264\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/dav-3\/\" class=\"wp-image-264\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4-920x920.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4-600x600.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4-768x768.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/4-TEXTA-SHOWROOM-4.jpg 1000w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">TEXTA &#8211; Showroom e uffici &#8211; Mercallo \/ Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"620\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2-920x620.jpg\" alt=\"\" data-id=\"265\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/5-texta-showroom-2\/\" class=\"wp-image-265\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2-920x620.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2-600x404.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2-768x517.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/5-TEXTA-SHOWROOM-2.jpg 1485w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">TEXTA &#8211; Showroom e uffici &#8211; Mercallo \/ Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"599\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1-920x599.jpg\" alt=\"\" data-id=\"266\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/6-texta-showroom-1\/\" class=\"wp-image-266\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1-920x599.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1-600x390.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1-460x300.jpg 460w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1-768x500.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/6-TEXTA-SHOWROOM-1.jpg 1537w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">TEXTA &#8211; Showroom e uffici &#8211; Mercallo \/ Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"460\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1-920x460.jpg\" alt=\"\" data-id=\"267\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/7-disano-1\/\" class=\"wp-image-267\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1-920x460.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1-600x300.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1-768x384.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1-1536x768.jpg 1536w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/7-DISANO-1.jpg 2000w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">DISANO &#8211; Showroom &#8211; Rozzano \/ Milano<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2-608x920.jpg\" alt=\"\" data-id=\"268\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/8-disano-2\/\" class=\"wp-image-268\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2-608x920.jpg 608w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2-397x600.jpg 397w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/8-DISANO-2.jpg 661w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">DISANO &#8211; Showroom &#8211; Rozzano \/ Milano<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"784\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1-920x784.jpg\" alt=\"\" data-id=\"269\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/9-ge-showroom-1\/\" class=\"wp-image-269\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1-920x784.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1-600x511.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1-768x654.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/9-GE-SHOWROOM-1.jpg 1174w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">GE LIGHTING &#8211; Edison Center &#8211; Budapest<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"614\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4-920x614.jpg\" alt=\"\" data-id=\"270\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/10-ge-showroom-4\/\" class=\"wp-image-270\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4-920x614.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4-600x400.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4-768x512.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/10-GE-SHOWROOM-4.jpg 1499w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">GE LIGHTING &#8211; Edison Center &#8211; Budapest<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"613\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3-920x613.jpg\" alt=\"\" data-id=\"271\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/11-ge-showroom-3\/\" class=\"wp-image-271\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3-920x613.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3-600x400.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3-768x512.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/11-GE-SHOWROOM-3.jpg 1500w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">GE LIGHTING &#8211; Edison Center &#8211; Budapest<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"612\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2-920x612.jpg\" alt=\"\" data-id=\"272\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/12-ge-showroom-2\/\" class=\"wp-image-272\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2-920x612.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2-600x399.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2-768x511.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/12-GE-SHOWROOM-2.jpg 1503w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">GE LIGHTING &#8211; Edison Center &#8211; Budapest<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"726\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1-920x726.jpg\" alt=\"\" data-id=\"273\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/sdr-2\/\" class=\"wp-image-273\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1-920x726.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1-600x473.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1-768x606.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/13-LEGGIUNO-ARCHIVIO-1.jpg 1268w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">LEGGIUNO- Sala Archivio &#8211; Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2-690x920.jpg\" alt=\"\" data-id=\"274\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/sdr-3\/\" class=\"wp-image-274\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2-690x920.jpg 690w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2-450x600.jpg 450w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/14-LEGGIUNO-ARCHIVIO-2.jpg 750w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">LEGGIUNO &#8211; Sala Archivio &#8211; Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3-690x920.jpg\" alt=\"\" data-id=\"275\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/sdr-4\/\" class=\"wp-image-275\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3-690x920.jpg 690w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3-450x600.jpg 450w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/15-LEGGIUNO-ARCHIVIO-3.jpg 750w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">LEGGIUNO &#8211; Sala Archivio &#8211; Varese<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"804\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1-920x804.jpg\" alt=\"\" data-id=\"276\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/16-emanuel-1\/\" class=\"wp-image-276\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1-920x804.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1-600x524.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1-768x671.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/16-EMANUEL-1.jpg 1144w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">EMANUEL JEANS &#8211; Flagship store &#8211; Milano<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"804\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2-920x804.jpg\" alt=\"\" data-id=\"277\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/17-emanuel-2\/\" class=\"wp-image-277\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2-920x804.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2-600x524.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2-768x671.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/17-EMANUEL-2.jpg 1144w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">EMANUEL JEANS &#8211; Flagship store &#8211; Milano<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"612\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO-920x612.jpg\" alt=\"\" data-id=\"278\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/18-light-studio-milano\/\" class=\"wp-image-278\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO-920x612.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO-600x399.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO-768x511.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/18-LIGHT-STUDIO-MILANO.jpg 1504w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">OSRAM &#8211; Light Studio &#8211; Milano<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"409\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-920x409.jpg\" alt=\"\" data-id=\"279\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/19-osram-lms-1\/\" class=\"wp-image-279\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-920x409.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-600x267.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-768x341.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-1536x683.jpg 1536w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/19-OSRAM-LMS-1-2048x910.jpg 2048w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">OSRAM &#8211; Light Studio &#8211; Treviso<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"614\" height=\"920\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3-614x920.jpg\" alt=\"\" data-id=\"280\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/20-osram-lms-3\/\" class=\"wp-image-280\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3-614x920.jpg 614w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3-400x600.jpg 400w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/20-OSRAM-LMS-3.jpg 667w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">OSRAM &#8211; Light Studio &#8211; Treviso<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"613\" src=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2-920x613.jpg\" alt=\"\" data-id=\"281\" data-full-url=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2.jpg\" data-link=\"https:\/\/www.lidealeallestimenti.it\/showroom-negozi\/21-osram-lms-2\/\" class=\"wp-image-281\" srcset=\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2-920x613.jpg 920w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2-600x400.jpg 600w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2-768x512.jpg 768w, https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/21-OSRAM-LMS-2.jpg 1500w\" sizes=\"(max-width: 920px) 100vw, 920px\" \/><\/a><figcaption class=\"blocks-gallery-item__caption\">OSRAM &#8211; Light Studio &#8211; Treviso<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Progettazione, allestimento e arredi su misura di spazi espositivi Spazi commerciali, bar, ristoranti, ambienti di lavoro e per l\u2019accoglienza, temporary shop e showroom. Soluzioni sempre in evidenza per il design innovativo, sviluppate nel rispetto delle valutazioni economiche assegnate e in base alle necessit\u00e0 del cliente.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Showroom &amp; Negozi - L&#039;ideale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Showroom &amp; Negozi - L&#039;ideale\" \/>\n<meta property=\"og:description\" content=\"Progettazione, allestimento e arredi su misura di spazi espositivi Spazi commerciali, bar, ristoranti, ambienti di lavoro e per l\u2019accoglienza, temporary shop e showroom. Soluzioni sempre in evidenza per il design innovativo, sviluppate nel rispetto delle valutazioni economiche assegnate e in base alle necessit\u00e0 del cliente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/\" \/>\n<meta property=\"og:site_name\" content=\"L&#039;ideale\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T09:30:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-920x616.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/\",\"url\":\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/\",\"name\":\"Showroom & Negozi - L&#039;ideale\",\"isPartOf\":{\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#website\"},\"datePublished\":\"2021-03-18T17:36:10+00:00\",\"dateModified\":\"2021-04-30T09:30:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/test.lidealeallestimenti.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Showroom &#038; Negozi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#website\",\"url\":\"https:\/\/test.lidealeallestimenti.it\/\",\"name\":\"L&#039;ideale\",\"description\":\"Allestimenti di stand fieristici e temporary shop\",\"publisher\":{\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.lidealeallestimenti.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#organization\",\"name\":\"L&#039;ideale\",\"url\":\"https:\/\/test.lidealeallestimenti.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/cropped-logo-lideale.png\",\"contentUrl\":\"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/cropped-logo-lideale.png\",\"width\":400,\"height\":142,\"caption\":\"L&#039;ideale\"},\"image\":{\"@id\":\"https:\/\/test.lidealeallestimenti.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Showroom & Negozi - L&#039;ideale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/","og_locale":"en_GB","og_type":"article","og_title":"Showroom & Negozi - L&#039;ideale","og_description":"Progettazione, allestimento e arredi su misura di spazi espositivi Spazi commerciali, bar, ristoranti, ambienti di lavoro e per l\u2019accoglienza, temporary shop e showroom. Soluzioni sempre in evidenza per il design innovativo, sviluppate nel rispetto delle valutazioni economiche assegnate e in base alle necessit\u00e0 del cliente.","og_url":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/","og_site_name":"L&#039;ideale","article_modified_time":"2021-04-30T09:30:15+00:00","og_image":[{"url":"https:\/\/test.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/1-THAT_S-ITALY-3-920x616.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/","url":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/","name":"Showroom & Negozi - L&#039;ideale","isPartOf":{"@id":"https:\/\/test.lidealeallestimenti.it\/#website"},"datePublished":"2021-03-18T17:36:10+00:00","dateModified":"2021-04-30T09:30:15+00:00","breadcrumb":{"@id":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.lidealeallestimenti.it\/showroom-negozi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.lidealeallestimenti.it\/"},{"@type":"ListItem","position":2,"name":"Showroom &#038; Negozi"}]},{"@type":"WebSite","@id":"https:\/\/test.lidealeallestimenti.it\/#website","url":"https:\/\/test.lidealeallestimenti.it\/","name":"L&#039;ideale","description":"Allestimenti di stand fieristici e temporary shop","publisher":{"@id":"https:\/\/test.lidealeallestimenti.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.lidealeallestimenti.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/test.lidealeallestimenti.it\/#organization","name":"L&#039;ideale","url":"https:\/\/test.lidealeallestimenti.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/test.lidealeallestimenti.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/cropped-logo-lideale.png","contentUrl":"https:\/\/www.lidealeallestimenti.it\/wp-content\/uploads\/2021\/03\/cropped-logo-lideale.png","width":400,"height":142,"caption":"L&#039;ideale"},"image":{"@id":"https:\/\/test.lidealeallestimenti.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/pages\/95"}],"collection":[{"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":6,"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/pages\/95\/revisions"}],"predecessor-version":[{"id":326,"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/pages\/95\/revisions\/326"}],"wp:attachment":[{"href":"https:\/\/www.lidealeallestimenti.it\/en\/wp-json\/wp\/v2\/media?parent=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}